{"id":5796,"date":"2026-07-15T12:22:18","date_gmt":"2026-07-15T10:22:18","guid":{"rendered":"http:\/\/time-girls.de\/?p=5796"},"modified":"2026-07-15T12:24:36","modified_gmt":"2026-07-15T10:24:36","slug":"sophie","status":"publish","type":"post","link":"http:\/\/time-girls.de\/fr\/sophie\/","title":{"rendered":"Sophie"},"content":{"rendered":"\n<p>Ganz neu bei uns \u00a0die Sophie.<br>Sie hat einen Geilen und \u00a0Erotischen \u00a0K\u00f6rper<br>und eine Wunderh\u00fcbsches Gesicht.<\/p>\n\n\n\n<p>F\u00fcr die Buchung eines Haus- oder Hotelbesuche oder Begleitservice<br>bitte anrufen.<br>Konkrete Information bitte telefonisch abkl\u00e4ren.<br>Tel: +4915204808888<\/p>\n\n\n\n<h4>Ich berechne f\u00fcr Freiburg Stadt:<br>30 &nbsp;Minuten &nbsp;\u2013 &nbsp;100 \u20ac<br>45 &nbsp; Minuten &nbsp;\u2013 &nbsp;130 \u20ac<br>60 &nbsp;Minuten &nbsp;\u2013 &nbsp;150 \u20ac,<br>zuz\u00fcglich der Anfahrtskosten!<\/h4>\n\n\n\n<h4>Buchungen Au\u00dferhalb Freiburg ab:<br>60 Minuten \u2013 150 \u20ac,<br>zuz\u00fcglich der Anfahrtskosten!<\/h4>\n\n\n\n<p>Zus\u00e4tzlich biete ich Dir einige &nbsp;EXTRASERVICES an,<br>die Du mit mir Pers\u00f6nlich zu vereinbaren hast. ( siehe oben im Profil )<br>Je nach Dauer der Buchungszeit biete ich Dir Einige &nbsp;<strong>GRATIS &nbsp;EXTRASERVICES<\/strong> an,<br>Welche das sind m\u00fcssten wir beide Pers\u00f6nlich besprechen!!<\/p>\n\n\n\n<p>Du kannst die Damen auch im Haus besuchen:<br><a href=\"http:\/\/www.villa15-deluxe.de\" target=\"_blank\" rel=\"noreferrer noopener\">www.villa15-deluxe.de<\/a><\/p>\n\n\n\n<p><img loading=\"lazy\" width=\"295\" height=\"127\" src=\"http:\/\/time-girls.de\/wp-content\/uploads\/2022\/01\/girocard_neu_klein.jpeg\" alt=\"\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"http:\/\/time-girls.de\/wp-content\/uploads\/2024\/10\/kondompflicht-1.png\"><img loading=\"lazy\" src=\"http:\/\/time-girls.de\/wp-content\/uploads\/2024\/10\/kondompflicht-1.png\" alt=\"\" class=\"wp-image-5422\" width=\"300\" height=\"162\" srcset=\"http:\/\/time-girls.de\/wp-content\/uploads\/2024\/10\/kondompflicht-1.png 922w, http:\/\/time-girls.de\/wp-content\/uploads\/2024\/10\/kondompflicht-1-300x163.png 300w, http:\/\/time-girls.de\/wp-content\/uploads\/2024\/10\/kondompflicht-1-768x416.png 768w, http:\/\/time-girls.de\/wp-content\/uploads\/2024\/10\/kondompflicht-1-370x201.png 370w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Ganz neu bei uns \u00a0die Sophie.Sie hat einen Geilen und \u00a0Erotischen \u00a0K\u00f6rperund eine Wunderh\u00fcbsches Gesicht. F\u00fcr die Buchung eines Haus- oder Hotelbesuche oder Begleitservicebitte anrufen.Konkrete Information bitte telefonisch abkl\u00e4ren.Tel: +4915204808888 Ich berechne f\u00fcr Freiburg Stadt:30[&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":5811,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[19,25,12,13,11,7,26,3,15,5,17,9,18,22,23,20,16,28,62,8,27,14,21,24],"_links":{"self":[{"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/posts\/5796"}],"collection":[{"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/comments?post=5796"}],"version-history":[{"count":1,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/posts\/5796\/revisions"}],"predecessor-version":[{"id":5797,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/posts\/5796\/revisions\/5797"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/media\/5811"}],"wp:attachment":[{"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/media?parent=5796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/categories?post=5796"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/time-girls.de\/fr\/wp-json\/wp\/v2\/tags?post=5796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}